{"id":10261,"date":"2019-09-19T09:55:02","date_gmt":"2019-09-19T07:55:02","guid":{"rendered":"https:\/\/jorntrahus.se\/?p=10261"},"modified":"2022-03-17T15:41:31","modified_gmt":"2022-03-17T14:41:31","slug":"interessant-byggetur-pa-alderholmen","status":"publish","type":"post","link":"https:\/\/jorntrahus.se\/nb\/inspiration\/intressant-byggresa-pa-alderholmen\/","title":{"rendered":"Interessant byggetur p\u00e5 Alderholmen"},"content":{"rendered":"<div class=\"row\"  id=\"row-2120929254\">\n\n\t<div id=\"col-2096493015\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Kunderapport Bergsholmen L<\/h2>\n<h3><b>- I ettertid angrer vi ikke p\u00e5 at vi tenkte stort og investerte dristig, vi har f\u00e5tt et fantastisk hus rett og slett, sier de to lykkelige 1TP1-eierne Nicolina og Per Bostr\u00f6m.<\/b><\/h3>\n<p>- Det faktum at Bergsholmen var den f\u00f8rste i sitt slag, har naturligvis f\u00f8rt til at vi personlig har blitt ekstra involvert i hvordan et t\u00f8mmerhus av denne st\u00f8rrelsen best bygges, en virkelig spennende og interessant reise der teorier og praktiske l\u00f8sninger har g\u00e5tt h\u00e5nd i h\u00e5nd gjennom hele prosessen, sier Per.<\/p>\n<p>- Det nye hjemmet v\u00e5rt har blitt litt \u201dtalk of the town\u201d i l\u00f8pet av byggeperioden, og mange har ogs\u00e5 fulgt oss p\u00e5 sosiale medier, noe vi har satt stor pris p\u00e5 ettersom vi har f\u00e5tt mye st\u00f8tte, kommentarer og spennende sp\u00f8rsm\u00e5l underveis, fortsetter Per.<\/p>\n<h4>Nesten surrealistisk<\/h4>\n<p>- \u00c5 v\u00e5kne opp sammen med familien den f\u00f8rste morgenen i det nye huset var bare s\u00e5 kult, nesten surrealistisk, n\u00e5 bor vi i det huset vi hadde tenkt \u00e5 bo i, og lar barna v\u00e5re vokse opp i akkurat slik vi planla for to \u00e5r siden, avslutter Nicolina.<\/p>\n<p>F\u00f8lg familiens husbygging p\u00e5 Instagram <a href=\"https:\/\/www.instagram.com\/bostromsjorntrahus\" target=\"_blank\" rel=\"noopener noreferrer\">@bostromsjorntrahus<\/a><\/p>\n\t<div id=\"gap-1334983031\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1334983031 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle align-center\"  id=\"row-1400884477\">\n\n\t<div id=\"col-1055848002\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_858491516\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-26.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport feriehus t\u00f8mmerhussett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-26.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-26-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-26-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-26-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-26-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_858491516 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1687246718\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_439889164\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-25.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport feriehus t\u00f8mmerhussett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-25.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-25-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-25-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-25-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-25-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_439889164 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2114457224\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1224681252\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-09.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport feriehus t\u00f8mmerhussett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-09.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-09-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-09-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-09-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-09-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1224681252 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1629135303\">\n\n\t<div id=\"col-1697246914\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_114458997\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-05.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport Bygg t\u00f8mmerhus byggesett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-05.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-05-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-05-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-05-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-05-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_114458997 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-48365411\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1757349822\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-19.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport feriehus t\u00f8mmerhussett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-19.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-19-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-19-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-19-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-19-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1757349822 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-687718157\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2079998122\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-24.jpg\" class=\"attachment-large size-large\" alt=\"Timmerknut - Kunderapport feriehus t\u00f8mmerhussett Bergsholmen Family Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-24.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-24-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-24-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-24-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-24-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2079998122 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1008287904\">\n\n\t<div id=\"col-1102368329\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_111231594\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-17.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport feriehus t\u00f8mmerhussett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-17.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-17-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-17-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-17-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-17-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_111231594 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1959144586\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1384402409\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-07.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport Bygg t\u00f8mmerhus byggesett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-07.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-07-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-07-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-07-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-07-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1384402409 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-657237828\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1409140261\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-22.jpg\" class=\"attachment-large size-large\" alt=\"Kunderapport feriehus t\u00f8mmerhussett Bergsholmen Familjen Bostr\u00f6m 2019\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-22.jpg 800w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-22-100x100.jpg 100w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-22-300x300.jpg 300w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-22-600x600.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bergsholmen-Familjen-Bostr\u00f6m-2019-webb-22-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1409140261 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1980314914\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1980314914 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-653805344\">\n\n\t<div id=\"col-1860313650\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/nb\/inspirasjon\/nicolina-og-pers-konstruksjonsreise-2\/\" class=\"button primary is-outline expand\" >\n\t\t<span>Reportasje del 1<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1311705216\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/nb\/husmodell\/bergsholmen-l\/\" class=\"button primary is-outline expand\" >\n\t\t<span>Mer om Bergsholmen<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1778151820\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/nb\/inspirasjon\/\" class=\"button primary is-outline expand\" >\n\t\t<span>Flere kundehistorier<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1453584608\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1453584608 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2017\/12\/Bergsholmen-L-3D.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2017\/12\/Bergsholmen-L-3D.jpg 1500w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2017\/12\/Bergsholmen-L-3D-600x400.jpg 600w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2017\/12\/Bergsholmen-L-3D-900x600.jpg 900w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2017\/12\/Bergsholmen-L-3D-768x512.jpg 768w, https:\/\/jorntrahus.se\/wp-content\/uploads\/2017\/12\/Bergsholmen-L-3D-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Bergsholmen-husmodellen<\/h4>\n<p>Bostr\u00f6m-familien baserte sitt spesialtilpassede hus p\u00e5 denne modellen.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>- I ettertid angrer vi ikke p\u00e5 at vi tenkte stort og investerte dristig, vi har f\u00e5tt et fantastisk hus rett og slett, sier de to lykkelige 1TP1-eierne Nicolina og Per Bostr\u00f6m.<\/p>","protected":false},"author":2,"featured_media":11345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[611],"tags":[1064,1046,1066,479],"class_list":["post-10261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration","tag-bergsholmen-l","tag-kundanpassning","tag-kundreportage","tag-timmerhus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intressant byggresa p\u00e5 Alderholmen - J\u00f6rntr\u00e4hus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jorntrahus.se\/nb\/inspirasjon\/interessant-byggetur-pa-alderholmen\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intressant byggresa p\u00e5 Alderholmen - J\u00f6rntr\u00e4hus\" \/>\n<meta property=\"og:description\" content=\"\u2013 Med facit i hand s\u00e5 \u00e5ngrar vi inte att vi t\u00e4nkte stort och satsade friskt, vi har f\u00e5tt ett fantastiskt hus helt enkelt, s\u00e4ger de tv\u00e5 glada J\u00f6rntr\u00e4hus\u00e4garna Nicolina och Per Bostr\u00f6m.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jorntrahus.se\/nb\/inspirasjon\/interessant-byggetur-pa-alderholmen\/\" \/>\n<meta property=\"og:site_name\" content=\"J\u00f6rntr\u00e4hus\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-19T07:55:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-17T14:41:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1826\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00f6rntr\u00e4hus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skrevet av\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00f6rntr\u00e4hus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/\"},\"author\":{\"name\":\"J\u00f6rntr\u00e4hus\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#\\\/schema\\\/person\\\/1d486a26d13d4df455271c2f02f5ef5c\"},\"headline\":\"Intressant byggresa p\u00e5 Alderholmen\",\"datePublished\":\"2019-09-19T07:55:02+00:00\",\"dateModified\":\"2022-03-17T14:41:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg\",\"keywords\":[\"Bergsholmen L\",\"kundanpassning\",\"kundreportage\",\"timmerhus\"],\"articleSection\":[\"Inspiration\"],\"inLanguage\":\"nb-NO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/\",\"url\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/\",\"name\":\"Intressant byggresa p\u00e5 Alderholmen - J\u00f6rntr\u00e4hus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg\",\"datePublished\":\"2019-09-19T07:55:02+00:00\",\"dateModified\":\"2022-03-17T14:41:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg\",\"width\":2560,\"height\":1826,\"caption\":\"Kundreportage Familjen Bostr\u00f6ms timmerhus Bergsholmen - reportage 2019\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/inspiration\\\/intressant-byggresa-pa-alderholmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/jorntrahus.se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intressant byggresa p\u00e5 Alderholmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#website\",\"url\":\"https:\\\/\\\/jorntrahus.se\\\/\",\"name\":\"J\u00f6rntr\u00e4hus\",\"description\":\"Hus f\u00f6r den medvetne\",\"publisher\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jorntrahus.se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#organization\",\"name\":\"J\u00f6rntr\u00e4hus\",\"url\":\"https:\\\/\\\/jorntrahus.se\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Jorntrahus_Grund_CMYK.eps\",\"contentUrl\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Jorntrahus_Grund_CMYK.eps\",\"width\":1,\"height\":1,\"caption\":\"J\u00f6rntr\u00e4hus\"},\"image\":{\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/#\\\/schema\\\/person\\\/1d486a26d13d4df455271c2f02f5ef5c\",\"name\":\"J\u00f6rntr\u00e4hus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/litespeed\\\/avatar\\\/1\\\/c9fe0b777387b9f19fec9d47d74fd6e0.jpg?ver=1778052376\",\"url\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/litespeed\\\/avatar\\\/1\\\/c9fe0b777387b9f19fec9d47d74fd6e0.jpg?ver=1778052376\",\"contentUrl\":\"https:\\\/\\\/jorntrahus.se\\\/wp-content\\\/litespeed\\\/avatar\\\/1\\\/c9fe0b777387b9f19fec9d47d74fd6e0.jpg?ver=1778052376\",\"caption\":\"J\u00f6rntr\u00e4hus\"},\"sameAs\":[\"https:\\\/\\\/jorntrahus.se\"],\"url\":\"https:\\\/\\\/jorntrahus.se\\\/nb\\\/author\\\/jorntrahus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interessant anleggstur p\u00e5 Alderholmen - J\u00f6rntr\u00e4hus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jorntrahus.se\/nb\/inspirasjon\/interessant-byggetur-pa-alderholmen\/","og_locale":"nb_NO","og_type":"article","og_title":"Intressant byggresa p\u00e5 Alderholmen - J\u00f6rntr\u00e4hus","og_description":"\u2013 Med facit i hand s\u00e5 \u00e5ngrar vi inte att vi t\u00e4nkte stort och satsade friskt, vi har f\u00e5tt ett fantastiskt hus helt enkelt, s\u00e4ger de tv\u00e5 glada J\u00f6rntr\u00e4hus\u00e4garna Nicolina och Per Bostr\u00f6m.","og_url":"https:\/\/jorntrahus.se\/nb\/inspirasjon\/interessant-byggetur-pa-alderholmen\/","og_site_name":"J\u00f6rntr\u00e4hus","article_published_time":"2019-09-19T07:55:02+00:00","article_modified_time":"2022-03-17T14:41:31+00:00","og_image":[{"width":2560,"height":1826,"url":"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg","type":"image\/jpeg"}],"author":"J\u00f6rntr\u00e4hus","twitter_card":"summary_large_image","twitter_misc":{"Skrevet av":"J\u00f6rntr\u00e4hus","Ansl. lesetid":"2 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/#article","isPartOf":{"@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/"},"author":{"name":"J\u00f6rntr\u00e4hus","@id":"https:\/\/jorntrahus.se\/#\/schema\/person\/1d486a26d13d4df455271c2f02f5ef5c"},"headline":"Intressant byggresa p\u00e5 Alderholmen","datePublished":"2019-09-19T07:55:02+00:00","dateModified":"2022-03-17T14:41:31+00:00","mainEntityOfPage":{"@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/"},"wordCount":434,"publisher":{"@id":"https:\/\/jorntrahus.se\/#organization"},"image":{"@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/#primaryimage"},"thumbnailUrl":"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg","keywords":["Bergsholmen L","kundanpassning","kundreportage","timmerhus"],"articleSection":["Inspiration"],"inLanguage":"nb-NO"},{"@type":"WebPage","@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/","url":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/","name":"Interessant anleggstur p\u00e5 Alderholmen - J\u00f6rntr\u00e4hus","isPartOf":{"@id":"https:\/\/jorntrahus.se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/#primaryimage"},"image":{"@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/#primaryimage"},"thumbnailUrl":"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg","datePublished":"2019-09-19T07:55:02+00:00","dateModified":"2022-03-17T14:41:31+00:00","breadcrumb":{"@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/"]}]},{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/#primaryimage","url":"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg","contentUrl":"https:\/\/jorntrahus.se\/wp-content\/uploads\/2019\/09\/Kundreportage-Bostr\u00f6ms-Bergsholmen-2019-01-webb-ver2-scaled.jpg","width":2560,"height":1826,"caption":"Kundreportage Familjen Bostr\u00f6ms timmerhus Bergsholmen - reportage 2019"},{"@type":"BreadcrumbList","@id":"https:\/\/jorntrahus.se\/inspiration\/intressant-byggresa-pa-alderholmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/jorntrahus.se\/"},{"@type":"ListItem","position":2,"name":"Intressant byggresa p\u00e5 Alderholmen"}]},{"@type":"WebSite","@id":"https:\/\/jorntrahus.se\/#website","url":"https:\/\/jorntrahus.se\/","name":"J\u00f6rntr\u00e4hus","description":"Hus for de bevisste","publisher":{"@id":"https:\/\/jorntrahus.se\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jorntrahus.se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/jorntrahus.se\/#organization","name":"J\u00f6rntr\u00e4hus","url":"https:\/\/jorntrahus.se\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/jorntrahus.se\/#\/schema\/logo\/image\/","url":"https:\/\/jorntrahus.se\/wp-content\/uploads\/2020\/09\/Jorntrahus_Grund_CMYK.eps","contentUrl":"https:\/\/jorntrahus.se\/wp-content\/uploads\/2020\/09\/Jorntrahus_Grund_CMYK.eps","width":1,"height":1,"caption":"J\u00f6rntr\u00e4hus"},"image":{"@id":"https:\/\/jorntrahus.se\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jorntrahus.se\/#\/schema\/person\/1d486a26d13d4df455271c2f02f5ef5c","name":"J\u00f6rntr\u00e4hus","image":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/jorntrahus.se\/wp-content\/litespeed\/avatar\/1\/c9fe0b777387b9f19fec9d47d74fd6e0.jpg?ver=1778052376","url":"https:\/\/jorntrahus.se\/wp-content\/litespeed\/avatar\/1\/c9fe0b777387b9f19fec9d47d74fd6e0.jpg?ver=1778052376","contentUrl":"https:\/\/jorntrahus.se\/wp-content\/litespeed\/avatar\/1\/c9fe0b777387b9f19fec9d47d74fd6e0.jpg?ver=1778052376","caption":"J\u00f6rntr\u00e4hus"},"sameAs":["https:\/\/jorntrahus.se"],"url":"https:\/\/jorntrahus.se\/nb\/author\/jorntrahus\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-17 17:10:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/posts\/10261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/comments?post=10261"}],"version-history":[{"count":11,"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/posts\/10261\/revisions"}],"predecessor-version":[{"id":11380,"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/posts\/10261\/revisions\/11380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/media\/11345"}],"wp:attachment":[{"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/media?parent=10261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/categories?post=10261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jorntrahus.se\/nb\/wp-json\/wp\/v2\/tags?post=10261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}